{"id":100,"date":"2022-10-24T15:47:25","date_gmt":"2022-10-24T14:47:25","guid":{"rendered":"https:\/\/lgbtq-insight-project.eu\/?page_id=100"},"modified":"2022-11-05T08:57:44","modified_gmt":"2022-11-05T08:57:44","slug":"newsletters","status":"publish","type":"page","link":"https:\/\/lgbtq-insight-project.eu\/el\/newsletters\/","title":{"rendered":"Newsletters"},"content":{"rendered":"<div class=\"vc_row wpb_row vc_row-fluid\"><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n<div class=\"vc_grid-container-wrapper vc_clearfix vc_grid-animation-fadeIn\">\n\t<div class=\"vc_grid-container vc_clearfix wpb_content_element vc_basic_grid\" data-initial-loading-animation=\"fadeIn\" data-vc-grid-settings=\"{&quot;page_id&quot;:100,&quot;style&quot;:&quot;all&quot;,&quot;action&quot;:&quot;vc_get_vc_grid_data&quot;,&quot;shortcode_id&quot;:&quot;1667638647062-ed3de9cd-3948-4&quot;,&quot;tag&quot;:&quot;vc_basic_grid&quot;}\" data-vc-request=\"https:\/\/lgbtq-insight-project.eu\/wp-admin\/admin-ajax.php\" data-vc-post-id=\"100\" data-vc-public-nonce=\"2db52f426a\">\n\t\t<style data-type=\"vc_shortcodes-custom-css\">.vc_custom_1419240516480{background-color: #f9f9f9 !important;}<\/style><div class=\"vc_grid vc_row vc_grid-gutter-30px vc_pageable-wrapper vc_hook_hover\" data-vc-pageable-content=\"true\"><div class=\"vc_pageable-slide-wrapper vc_clearfix\" data-vc-grid-content=\"true\"><div class=\"vc_grid-item vc_clearfix vc_col-sm-4 vc_grid-item-zone-c-bottom\"><div class=\"vc_grid-item-mini vc_clearfix\"><div class=\"vc_gitem-animated-block\" ><div class=\"vc_gitem-zone vc_gitem-zone-a vc-gitem-zone-height-mode-auto vc-gitem-zone-height-mode-auto-4-3 vc_gitem-is-link\" style=\"background-image: url('https:\/\/lgbtq-insight-project.eu\/wp-content\/uploads\/2023\/11\/ENG-INSIGHT-4th-Newsletter-1-724x1024.png') !important;\"><a href=\"https:\/\/lgbtq-insight-project.eu\/el\/insight-newsletter-no-4\/\" title=\"INSIGHT Newsletter No 4\" class=\"vc_gitem-link vc-zone-link\" ><\/a><img src=\"https:\/\/lgbtq-insight-project.eu\/wp-content\/uploads\/2023\/11\/ENG-INSIGHT-4th-Newsletter-1-724x1024.png\" class=\"vc_gitem-zone-img\" alt=\"INSIGHT Newsletter No 4\"><div class=\"vc_gitem-zone-mini\"><\/div><\/div><\/div><div class=\"vc_gitem-zone vc_gitem-zone-c vc_custom_1419240516480\"><div class=\"vc_gitem-zone-mini\"><div class=\"vc_gitem_row vc_row vc_gitem-row-position-top\"><div class=\"vc_col-sm-12 vc_gitem-col vc_gitem-col-align-\"><div class=\"vc_custom_heading vc_gitem-post-data vc_gitem-post-data-source-post_title\" ><h4 style=\"text-align: left\" >INSIGHT Newsletter No 4<\/h4><\/div><div class=\"vc_custom_heading vc_gitem-post-data vc_gitem-post-data-source-post_excerpt\" ><p style=\"text-align: left\" ><\/p><\/div><div class=\"vc_btn3-container vc_btn3-left\"><a class=\"vc_general vc_btn3 vc_btn3-size-md vc_btn3-shape-rounded vc_btn3-style-flat vc_btn3-color-juicy-pink\" a href=\"https:\/\/lgbtq-insight-project.eu\/el\/insight-newsletter-no-4\/\" title=\"\u0394\u03b9\u03ac\u03b2\u03b1\u03c3\u03b5\">\u0394\u03b9\u03ac\u03b2\u03b1\u03c3\u03b5<\/a><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"vc_clearfix\"><\/div><\/div><div class=\"vc_grid-item vc_clearfix vc_col-sm-4 vc_grid-item-zone-c-bottom\"><div class=\"vc_grid-item-mini vc_clearfix\"><div class=\"vc_gitem-animated-block\" ><div class=\"vc_gitem-zone vc_gitem-zone-a vc-gitem-zone-height-mode-auto vc-gitem-zone-height-mode-auto-4-3 vc_gitem-is-link\" style=\"background-image: url('https:\/\/lgbtq-insight-project.eu\/wp-content\/uploads\/2023\/05\/INSIGHT-3-Newsletter-ENG-_Page_1-724x1024.jpg') !important;\"><a href=\"https:\/\/lgbtq-insight-project.eu\/el\/insight-newsletter-no-3\/\" title=\"INSIGHT Newsletter No 3\" class=\"vc_gitem-link vc-zone-link\" ><\/a><img src=\"https:\/\/lgbtq-insight-project.eu\/wp-content\/uploads\/2023\/05\/GR-INSIGHT-Newsletter-3-to-go-_Page_1-scaled.jpg\" class=\"vc_gitem-zone-img\" alt=\"INSIGHT #3 Newsletter ENG _Page_1\"><div class=\"vc_gitem-zone-mini\"><\/div><\/div><\/div><div class=\"vc_gitem-zone vc_gitem-zone-c vc_custom_1419240516480\"><div class=\"vc_gitem-zone-mini\"><div class=\"vc_gitem_row vc_row vc_gitem-row-position-top\"><div class=\"vc_col-sm-12 vc_gitem-col vc_gitem-col-align-\"><div class=\"vc_custom_heading vc_gitem-post-data vc_gitem-post-data-source-post_title\" ><h4 style=\"text-align: left\" >INSIGHT Newsletter No 3<\/h4><\/div><div class=\"vc_custom_heading vc_gitem-post-data vc_gitem-post-data-source-post_excerpt\" ><p style=\"text-align: left\" ><\/p><\/div><div class=\"vc_btn3-container vc_btn3-left\"><a class=\"vc_general vc_btn3 vc_btn3-size-md vc_btn3-shape-rounded vc_btn3-style-flat vc_btn3-color-juicy-pink\" a href=\"https:\/\/lgbtq-insight-project.eu\/el\/insight-newsletter-no-3\/\" title=\"\u0394\u03b9\u03ac\u03b2\u03b1\u03c3\u03b5\">\u0394\u03b9\u03ac\u03b2\u03b1\u03c3\u03b5<\/a><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"vc_clearfix\"><\/div><\/div><div class=\"vc_grid-item vc_clearfix vc_col-sm-4 vc_grid-item-zone-c-bottom\"><div class=\"vc_grid-item-mini vc_clearfix\"><div class=\"vc_gitem-animated-block\" ><div class=\"vc_gitem-zone vc_gitem-zone-a vc-gitem-zone-height-mode-auto vc-gitem-zone-height-mode-auto-4-3 vc_gitem-is-link\" style=\"background-image: url('https:\/\/lgbtq-insight-project.eu\/wp-content\/uploads\/2022\/12\/2nd-Newsletter-ENG_Page_1-720x1024.jpg') !important;\"><a href=\"https:\/\/lgbtq-insight-project.eu\/el\/insight-newsletter-no-2\/\" title=\"INSIGHT Newsletter No 2\" class=\"vc_gitem-link vc-zone-link\" ><\/a><img src=\"https:\/\/lgbtq-insight-project.eu\/wp-content\/uploads\/2022\/12\/2nd-Newsletter-ENG_Page_1-720x1024.jpg\" class=\"vc_gitem-zone-img\" alt=\"2nd Newsletter ENG_Page_1\"><div class=\"vc_gitem-zone-mini\"><\/div><\/div><\/div><div class=\"vc_gitem-zone vc_gitem-zone-c vc_custom_1419240516480\"><div class=\"vc_gitem-zone-mini\"><div class=\"vc_gitem_row vc_row vc_gitem-row-position-top\"><div class=\"vc_col-sm-12 vc_gitem-col vc_gitem-col-align-\"><div class=\"vc_custom_heading vc_gitem-post-data vc_gitem-post-data-source-post_title\" ><h4 style=\"text-align: left\" >INSIGHT Newsletter No 2<\/h4><\/div><div class=\"vc_custom_heading vc_gitem-post-data vc_gitem-post-data-source-post_excerpt\" ><p style=\"text-align: left\" ><\/p><\/div><div class=\"vc_btn3-container vc_btn3-left\"><a class=\"vc_general vc_btn3 vc_btn3-size-md vc_btn3-shape-rounded vc_btn3-style-flat vc_btn3-color-juicy-pink\" a href=\"https:\/\/lgbtq-insight-project.eu\/el\/insight-newsletter-no-2\/\" title=\"\u0394\u03b9\u03ac\u03b2\u03b1\u03c3\u03b5\">\u0394\u03b9\u03ac\u03b2\u03b1\u03c3\u03b5<\/a><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"vc_clearfix\"><\/div><\/div><div class=\"vc_grid-item vc_clearfix vc_col-sm-4 vc_grid-item-zone-c-bottom\"><div class=\"vc_grid-item-mini vc_clearfix\"><div class=\"vc_gitem-animated-block\" ><div class=\"vc_gitem-zone vc_gitem-zone-a vc-gitem-zone-height-mode-auto vc-gitem-zone-height-mode-auto-4-3 vc_gitem-is-link\" style=\"background-image: url('https:\/\/lgbtq-insight-project.eu\/wp-content\/uploads\/2022\/11\/1st-Newsletter-ENG_Page_1-724x1024.jpg') !important;\"><a href=\"https:\/\/lgbtq-insight-project.eu\/el\/insight-newsletter-no-1\/\" title=\"INSIGHT Newsletter No 1\" class=\"vc_gitem-link vc-zone-link\" ><\/a><img src=\"https:\/\/lgbtq-insight-project.eu\/wp-content\/uploads\/2022\/11\/1st-Newsletter-GRE_Page_1-scaled.jpg\" class=\"vc_gitem-zone-img\" alt=\"1st Newsletter ENG_Page_1\"><div class=\"vc_gitem-zone-mini\"><\/div><\/div><\/div><div class=\"vc_gitem-zone vc_gitem-zone-c vc_custom_1419240516480\"><div class=\"vc_gitem-zone-mini\"><div class=\"vc_gitem_row vc_row vc_gitem-row-position-top\"><div class=\"vc_col-sm-12 vc_gitem-col vc_gitem-col-align-\"><div class=\"vc_custom_heading vc_gitem-post-data vc_gitem-post-data-source-post_title\" ><h4 style=\"text-align: left\" >INSIGHT Newsletter No 1<\/h4><\/div><div class=\"vc_custom_heading vc_gitem-post-data vc_gitem-post-data-source-post_excerpt\" ><p style=\"text-align: left\" ><\/p><\/div><div class=\"vc_btn3-container vc_btn3-left\"><a class=\"vc_general vc_btn3 vc_btn3-size-md vc_btn3-shape-rounded vc_btn3-style-flat vc_btn3-color-juicy-pink\" a href=\"https:\/\/lgbtq-insight-project.eu\/el\/insight-newsletter-no-1\/\" title=\"\u0394\u03b9\u03ac\u03b2\u03b1\u03c3\u03b5\">\u0394\u03b9\u03ac\u03b2\u03b1\u03c3\u03b5<\/a><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"vc_clearfix\"><\/div><\/div><\/div><\/div>\n\t<\/div>\n<\/div><\/div><\/div><\/div><\/div>","protected":false},"excerpt":{"rendered":null,"protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"page-full.php","meta":{"footnotes":""},"_links":{"self":[{"href":"https:\/\/lgbtq-insight-project.eu\/el\/wp-json\/wp\/v2\/pages\/100"}],"collection":[{"href":"https:\/\/lgbtq-insight-project.eu\/el\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/lgbtq-insight-project.eu\/el\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/lgbtq-insight-project.eu\/el\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/lgbtq-insight-project.eu\/el\/wp-json\/wp\/v2\/comments?post=100"}],"version-history":[{"count":0,"href":"https:\/\/lgbtq-insight-project.eu\/el\/wp-json\/wp\/v2\/pages\/100\/revisions"}],"wp:attachment":[{"href":"https:\/\/lgbtq-insight-project.eu\/el\/wp-json\/wp\/v2\/media?parent=100"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}