{"id":18,"date":"2022-05-01T18:20:27","date_gmt":"2022-05-01T17:20:27","guid":{"rendered":"http:\/\/lgbtq-insight-project.eu\/?page_id=18"},"modified":"2022-07-15T09:28:35","modified_gmt":"2022-07-15T08:28:35","slug":"news-events","status":"publish","type":"page","link":"https:\/\/lgbtq-insight-project.eu\/el\/news-events\/","title":{"rendered":"\u039d\u03ad\u03b1 &amp; \u0395\u03ba\u03b4\u03b7\u03bb\u03ce\u03c3\u03b5\u03b9\u03c2"},"content":{"rendered":"<div class=\"vc_row wpb_row vc_row-fluid\"><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n<div class=\"vc_grid-container-wrapper vc_clearfix vc_grid-animation-fadeIn\">\n\t<div class=\"vc_grid-container vc_clearfix wpb_content_element vc_basic_grid\" data-initial-loading-animation=\"fadeIn\" data-vc-grid-settings=\"{&quot;page_id&quot;:18,&quot;style&quot;:&quot;all&quot;,&quot;action&quot;:&quot;vc_get_vc_grid_data&quot;,&quot;shortcode_id&quot;:&quot;1657873846859-f4c754d4-91d1-8&quot;,&quot;tag&quot;:&quot;vc_basic_grid&quot;}\" data-vc-request=\"https:\/\/lgbtq-insight-project.eu\/wp-admin\/admin-ajax.php\" data-vc-post-id=\"18\" data-vc-public-nonce=\"2db52f426a\">\n\t\t<style data-type=\"vc_shortcodes-custom-css\">.vc_custom_1419240516480{background-color: #f9f9f9 !important;}<\/style><div class=\"vc_grid vc_row vc_grid-gutter-30px vc_pageable-wrapper vc_hook_hover\" data-vc-pageable-content=\"true\"><div class=\"vc_pageable-slide-wrapper vc_clearfix\" data-vc-grid-content=\"true\"><div class=\"vc_grid-item vc_clearfix vc_col-sm-6 vc_grid-item-zone-c-bottom\"><div class=\"vc_grid-item-mini vc_clearfix\"><div class=\"vc_gitem-animated-block\" ><div class=\"vc_gitem-zone vc_gitem-zone-a vc-gitem-zone-height-mode-auto vc-gitem-zone-height-mode-auto-4-3 vc_gitem-is-link\" style=\"background-image: url('https:\/\/lgbtq-insight-project.eu\/wp-content\/uploads\/2023\/10\/image001-1024x683.jpg') !important;\"><a href=\"https:\/\/lgbtq-insight-project.eu\/el\/interview-with-ilan-meyer\/\" title=\"\u03a3\u03c5\u03bd\u03ad\u03bd\u03c4\u03b5\u03c5\u03be\u03b7 \u03bc\u03b5 \u03c4\u03bf\u03bd Ilan Meyer\" class=\"vc_gitem-link vc-zone-link\" ><\/a><img src=\"https:\/\/lgbtq-insight-project.eu\/wp-content\/uploads\/2023\/10\/image001-1024x683.jpg\" class=\"vc_gitem-zone-img\" alt=\"Interview with Ilan Meyer\"><div class=\"vc_gitem-zone-mini\"><\/div><\/div><\/div><div class=\"vc_gitem-zone vc_gitem-zone-c vc_custom_1419240516480\"><div class=\"vc_gitem-zone-mini\"><div class=\"vc_gitem_row vc_row vc_gitem-row-position-top\"><div class=\"vc_col-sm-12 vc_gitem-col vc_gitem-col-align-\"><div class=\"vc_custom_heading vc_gitem-post-data vc_gitem-post-data-source-post_title\" ><h4 style=\"text-align: left\" >\u03a3\u03c5\u03bd\u03ad\u03bd\u03c4\u03b5\u03c5\u03be\u03b7 \u03bc\u03b5 \u03c4\u03bf\u03bd Ilan Meyer<\/h4><\/div><div class=\"vc_custom_heading vc_gitem-post-data vc_gitem-post-data-source-post_excerpt\" ><p style=\"text-align: left\" ><\/p><\/div><div class=\"vc_btn3-container vc_btn3-left\"><a class=\"vc_general vc_btn3 vc_btn3-size-md vc_btn3-shape-rounded vc_btn3-style-flat vc_btn3-color-juicy-pink\" a href=\"https:\/\/lgbtq-insight-project.eu\/el\/interview-with-ilan-meyer\/\" title=\"\u0394\u03b9\u03ac\u03b2\u03b1\u03c3\u03b5\">\u0394\u03b9\u03ac\u03b2\u03b1\u03c3\u03b5<\/a><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"vc_clearfix\"><\/div><\/div><div class=\"vc_grid-item vc_clearfix vc_col-sm-6 vc_grid-item-zone-c-bottom\"><div class=\"vc_grid-item-mini vc_clearfix\"><div class=\"vc_gitem-animated-block\" ><div class=\"vc_gitem-zone vc_gitem-zone-a vc-gitem-zone-height-mode-auto vc-gitem-zone-height-mode-auto-4-3 vc_gitem-is-link\" style=\"background-image: url('https:\/\/lgbtq-insight-project.eu\/wp-content\/uploads\/2022\/05\/main-1-1024x683.jpg') !important;\"><a href=\"https:\/\/lgbtq-insight-project.eu\/el\/insight-final-conference-on-national-television\/\" title=\"INSIGHT Final Conference on National Television\" class=\"vc_gitem-link vc-zone-link\" ><\/a><img src=\"https:\/\/lgbtq-insight-project.eu\/wp-content\/uploads\/2022\/05\/main-1-1024x683.jpg\" class=\"vc_gitem-zone-img\" alt=\"main-1\"><div class=\"vc_gitem-zone-mini\"><\/div><\/div><\/div><div class=\"vc_gitem-zone vc_gitem-zone-c vc_custom_1419240516480\"><div class=\"vc_gitem-zone-mini\"><div class=\"vc_gitem_row vc_row vc_gitem-row-position-top\"><div class=\"vc_col-sm-12 vc_gitem-col vc_gitem-col-align-\"><div class=\"vc_custom_heading vc_gitem-post-data vc_gitem-post-data-source-post_title\" ><h4 style=\"text-align: left\" >INSIGHT Final Conference on National Television<\/h4><\/div><div class=\"vc_custom_heading vc_gitem-post-data vc_gitem-post-data-source-post_excerpt\" ><p style=\"text-align: left\" ><\/p><\/div><div class=\"vc_btn3-container vc_btn3-left\"><a class=\"vc_general vc_btn3 vc_btn3-size-md vc_btn3-shape-rounded vc_btn3-style-flat vc_btn3-color-juicy-pink\" a href=\"https:\/\/lgbtq-insight-project.eu\/el\/insight-final-conference-on-national-television\/\" title=\"\u0394\u03b9\u03ac\u03b2\u03b1\u03c3\u03b5\">\u0394\u03b9\u03ac\u03b2\u03b1\u03c3\u03b5<\/a><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"vc_clearfix\"><\/div><\/div><div class=\"vc_grid-item vc_clearfix vc_col-sm-6 vc_grid-item-zone-c-bottom\"><div class=\"vc_grid-item-mini vc_clearfix\"><div class=\"vc_gitem-animated-block\" ><div class=\"vc_gitem-zone vc_gitem-zone-a vc-gitem-zone-height-mode-auto vc-gitem-zone-height-mode-auto-4-3 vc_gitem-is-link\" style=\"background-image: url('https:\/\/lgbtq-insight-project.eu\/wp-content\/uploads\/2022\/12\/orlando-1-1024x576.jpg') !important;\"><a href=\"https:\/\/lgbtq-insight-project.eu\/el\/meet-the-consortium-partners-orlando-lgbt\/\" title=\"\u0393\u03bd\u03c9\u03c1\u03af\u03c3\u03c4\u03b5 \u03c4\u03bf\u03c5\u03c2 \u03b5\u03c4\u03b1\u03af\u03c1\u03bf\u03c5\u03c2 \u03c4\u03b7\u03c2 \u03ba\u03bf\u03b9\u03bd\u03bf\u03c0\u03c1\u03b1\u03be\u03af\u03b1\u03c2! Orlando LGBT+\" class=\"vc_gitem-link vc-zone-link\" ><\/a><img src=\"https:\/\/lgbtq-insight-project.eu\/wp-content\/uploads\/2022\/12\/orlando-1-1024x576.jpg\" class=\"vc_gitem-zone-img\" alt=\"orlando-1\"><div class=\"vc_gitem-zone-mini\"><\/div><\/div><\/div><div class=\"vc_gitem-zone vc_gitem-zone-c vc_custom_1419240516480\"><div class=\"vc_gitem-zone-mini\"><div class=\"vc_gitem_row vc_row vc_gitem-row-position-top\"><div class=\"vc_col-sm-12 vc_gitem-col vc_gitem-col-align-\"><div class=\"vc_custom_heading vc_gitem-post-data vc_gitem-post-data-source-post_title\" ><h4 style=\"text-align: left\" >\u0393\u03bd\u03c9\u03c1\u03af\u03c3\u03c4\u03b5 \u03c4\u03bf\u03c5\u03c2 \u03b5\u03c4\u03b1\u03af\u03c1\u03bf\u03c5\u03c2 \u03c4\u03b7\u03c2 \u03ba\u03bf\u03b9\u03bd\u03bf\u03c0\u03c1\u03b1\u03be\u03af\u03b1\u03c2! Orlando LGBT+<\/h4><\/div><div class=\"vc_custom_heading vc_gitem-post-data vc_gitem-post-data-source-post_excerpt\" ><p style=\"text-align: left\" ><\/p><\/div><div class=\"vc_btn3-container vc_btn3-left\"><a class=\"vc_general vc_btn3 vc_btn3-size-md vc_btn3-shape-rounded vc_btn3-style-flat vc_btn3-color-juicy-pink\" a href=\"https:\/\/lgbtq-insight-project.eu\/el\/meet-the-consortium-partners-orlando-lgbt\/\" title=\"\u0394\u03b9\u03ac\u03b2\u03b1\u03c3\u03b5\">\u0394\u03b9\u03ac\u03b2\u03b1\u03c3\u03b5<\/a><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"vc_clearfix\"><\/div><\/div><div class=\"vc_grid-item vc_clearfix vc_col-sm-6 vc_grid-item-zone-c-bottom\"><div class=\"vc_grid-item-mini vc_clearfix\"><div class=\"vc_gitem-animated-block\" ><div class=\"vc_gitem-zone vc_gitem-zone-a vc-gitem-zone-height-mode-auto vc-gitem-zone-height-mode-auto-4-3 vc_gitem-is-link\" style=\"background-image: url('https:\/\/lgbtq-insight-project.eu\/wp-content\/uploads\/2022\/11\/insvid-1024x575.jpg') !important;\"><a href=\"https:\/\/lgbtq-insight-project.eu\/el\/meet-the-consortium-partners-university-of-salerno\/\" title=\"\u0393\u03bd\u03c9\u03c1\u03af\u03c3\u03c4\u03b5 \u03c4\u03bf\u03c5\u03c2 \u03b5\u03c4\u03b1\u03af\u03c1\u03bf\u03c5\u03c2 \u03c4\u03b7\u03c2 \u03ba\u03bf\u03b9\u03bd\u03bf\u03c0\u03c1\u03b1\u03be\u03af\u03b1\u03c2! \u03a0\u03b1\u03bd\u03b5\u03c0\u03b9\u03c3\u03c4\u03ae\u03bc\u03b9\u03bf \u03c4\u03bf\u03c5 \u03a3\u03b1\u03bb\u03ad\u03c1\u03bd\u03bf\" class=\"vc_gitem-link vc-zone-link\" ><\/a><img src=\"https:\/\/lgbtq-insight-project.eu\/wp-content\/uploads\/2022\/11\/insvid-1024x575.jpg\" class=\"vc_gitem-zone-img\" alt=\"insvid\"><div class=\"vc_gitem-zone-mini\"><\/div><\/div><\/div><div class=\"vc_gitem-zone vc_gitem-zone-c vc_custom_1419240516480\"><div class=\"vc_gitem-zone-mini\"><div class=\"vc_gitem_row vc_row vc_gitem-row-position-top\"><div class=\"vc_col-sm-12 vc_gitem-col vc_gitem-col-align-\"><div class=\"vc_custom_heading vc_gitem-post-data vc_gitem-post-data-source-post_title\" ><h4 style=\"text-align: left\" >\u0393\u03bd\u03c9\u03c1\u03af\u03c3\u03c4\u03b5 \u03c4\u03bf\u03c5\u03c2 \u03b5\u03c4\u03b1\u03af\u03c1\u03bf\u03c5\u03c2 \u03c4\u03b7\u03c2 \u03ba\u03bf\u03b9\u03bd\u03bf\u03c0\u03c1\u03b1\u03be\u03af\u03b1\u03c2! \u03a0\u03b1\u03bd\u03b5\u03c0\u03b9\u03c3\u03c4\u03ae\u03bc\u03b9\u03bf \u03c4\u03bf\u03c5 \u03a3\u03b1\u03bb\u03ad\u03c1\u03bd\u03bf<\/h4><\/div><div class=\"vc_custom_heading vc_gitem-post-data vc_gitem-post-data-source-post_excerpt\" ><p style=\"text-align: left\" ><\/p><\/div><div class=\"vc_btn3-container vc_btn3-left\"><a class=\"vc_general vc_btn3 vc_btn3-size-md vc_btn3-shape-rounded vc_btn3-style-flat vc_btn3-color-juicy-pink\" a href=\"https:\/\/lgbtq-insight-project.eu\/el\/meet-the-consortium-partners-university-of-salerno\/\" title=\"\u0394\u03b9\u03ac\u03b2\u03b1\u03c3\u03b5\">\u0394\u03b9\u03ac\u03b2\u03b1\u03c3\u03b5<\/a><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"vc_clearfix\"><\/div><\/div><div class=\"vc_grid-item vc_clearfix vc_col-sm-6 vc_grid-item-zone-c-bottom\"><div class=\"vc_grid-item-mini vc_clearfix\"><div class=\"vc_gitem-animated-block\" ><div class=\"vc_gitem-zone vc_gitem-zone-a vc-gitem-zone-height-mode-auto vc-gitem-zone-height-mode-auto-4-3 vc_gitem-is-link\" style=\"background-image: url('https:\/\/lgbtq-insight-project.eu\/wp-content\/uploads\/2022\/11\/IT-Salerno-Journal-701x1024.png') !important;\"><a href=\"https:\/\/lgbtq-insight-project.eu\/el\/health-inequalities-in-the-lgbt-context\/\" title=\"\u039f\u03b9 \u03b1\u03bd\u03b9\u03c3\u03cc\u03c4\u03b7\u03c4\u03b5\u03c2 \u03c3\u03c4\u03b7\u03bd Y\u03b3\u03b5\u03af\u03b1 \u03c3\u03c4\u03bf \u03c0\u03bb\u03b1\u03af\u03c3\u03b9\u03bf \u03c4\u03c9\u03bd \u039b\u039f\u0391\u03a4\u039a\u0399+\" class=\"vc_gitem-link vc-zone-link\" ><\/a><img src=\"https:\/\/lgbtq-insight-project.eu\/wp-content\/uploads\/2022\/11\/IT-Salerno-Journal-701x1024.png\" class=\"vc_gitem-zone-img\" alt=\"IT Salerno Journal\"><div class=\"vc_gitem-zone-mini\"><\/div><\/div><\/div><div class=\"vc_gitem-zone vc_gitem-zone-c vc_custom_1419240516480\"><div class=\"vc_gitem-zone-mini\"><div class=\"vc_gitem_row vc_row vc_gitem-row-position-top\"><div class=\"vc_col-sm-12 vc_gitem-col vc_gitem-col-align-\"><div class=\"vc_custom_heading vc_gitem-post-data vc_gitem-post-data-source-post_title\" ><h4 style=\"text-align: left\" >\u039f\u03b9 \u03b1\u03bd\u03b9\u03c3\u03cc\u03c4\u03b7\u03c4\u03b5\u03c2 \u03c3\u03c4\u03b7\u03bd Y\u03b3\u03b5\u03af\u03b1 \u03c3\u03c4\u03bf \u03c0\u03bb\u03b1\u03af\u03c3\u03b9\u03bf \u03c4\u03c9\u03bd \u039b\u039f\u0391\u03a4\u039a\u0399+<\/h4><\/div><div class=\"vc_custom_heading vc_gitem-post-data vc_gitem-post-data-source-post_excerpt\" ><p style=\"text-align: left\" ><\/p><\/div><div class=\"vc_btn3-container vc_btn3-left\"><a class=\"vc_general vc_btn3 vc_btn3-size-md vc_btn3-shape-rounded vc_btn3-style-flat vc_btn3-color-juicy-pink\" a href=\"https:\/\/lgbtq-insight-project.eu\/el\/health-inequalities-in-the-lgbt-context\/\" title=\"\u0394\u03b9\u03ac\u03b2\u03b1\u03c3\u03b5\">\u0394\u03b9\u03ac\u03b2\u03b1\u03c3\u03b5<\/a><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"vc_clearfix\"><\/div><\/div><div class=\"vc_grid-item vc_clearfix vc_col-sm-6 vc_grid-item-zone-c-bottom\"><div class=\"vc_grid-item-mini vc_clearfix\"><div class=\"vc_gitem-animated-block\" ><div class=\"vc_gitem-zone vc_gitem-zone-a vc-gitem-zone-height-mode-auto vc-gitem-zone-height-mode-auto-4-3 vc_gitem-is-link\" style=\"background-image: url('https:\/\/lgbtq-insight-project.eu\/wp-content\/uploads\/2022\/11\/mcp-1024x571.jpg') !important;\"><a href=\"https:\/\/lgbtq-insight-project.eu\/el\/meet-the-consortium-partners-university-of-torino\/\" title=\"\u0393\u03bd\u03c9\u03c1\u03af\u03c3\u03c4\u03b5 \u03c4\u03bf\u03c5\u03c2 \u03b5\u03c4\u03b1\u03af\u03c1\u03bf\u03c5\u03c2 \u03c4\u03b7\u03c2 \u03ba\u03bf\u03b9\u03bd\u03bf\u03c0\u03c1\u03b1\u03be\u03af\u03b1\u03c2! \u03a0\u03b1\u03bd\u03b5\u03c0\u03b9\u03c3\u03c4\u03ae\u03bc\u03b9\u03bf \u03c4\u03bf\u03c5 \u03a4\u03bf\u03c1\u03af\u03bd\u03bf\" class=\"vc_gitem-link vc-zone-link\" ><\/a><img src=\"https:\/\/lgbtq-insight-project.eu\/wp-content\/uploads\/2022\/11\/mcp-1024x571.jpg\" class=\"vc_gitem-zone-img\" alt=\"mcp\"><div class=\"vc_gitem-zone-mini\"><\/div><\/div><\/div><div class=\"vc_gitem-zone vc_gitem-zone-c vc_custom_1419240516480\"><div class=\"vc_gitem-zone-mini\"><div class=\"vc_gitem_row vc_row vc_gitem-row-position-top\"><div class=\"vc_col-sm-12 vc_gitem-col vc_gitem-col-align-\"><div class=\"vc_custom_heading vc_gitem-post-data vc_gitem-post-data-source-post_title\" ><h4 style=\"text-align: left\" >\u0393\u03bd\u03c9\u03c1\u03af\u03c3\u03c4\u03b5 \u03c4\u03bf\u03c5\u03c2 \u03b5\u03c4\u03b1\u03af\u03c1\u03bf\u03c5\u03c2 \u03c4\u03b7\u03c2 \u03ba\u03bf\u03b9\u03bd\u03bf\u03c0\u03c1\u03b1\u03be\u03af\u03b1\u03c2! \u03a0\u03b1\u03bd\u03b5\u03c0\u03b9\u03c3\u03c4\u03ae\u03bc\u03b9\u03bf \u03c4\u03bf\u03c5 \u03a4\u03bf\u03c1\u03af\u03bd\u03bf<\/h4><\/div><div class=\"vc_custom_heading vc_gitem-post-data vc_gitem-post-data-source-post_excerpt\" ><p style=\"text-align: left\" ><\/p><\/div><div class=\"vc_btn3-container vc_btn3-left\"><a class=\"vc_general vc_btn3 vc_btn3-size-md vc_btn3-shape-rounded vc_btn3-style-flat vc_btn3-color-juicy-pink\" a href=\"https:\/\/lgbtq-insight-project.eu\/el\/meet-the-consortium-partners-university-of-torino\/\" title=\"\u0394\u03b9\u03ac\u03b2\u03b1\u03c3\u03b5\">\u0394\u03b9\u03ac\u03b2\u03b1\u03c3\u03b5<\/a><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"vc_clearfix\"><\/div><\/div><div class=\"vc_grid-item vc_clearfix vc_col-sm-6 vc_grid-item-zone-c-bottom\"><div class=\"vc_grid-item-mini vc_clearfix\"><div class=\"vc_gitem-animated-block\" ><div class=\"vc_gitem-zone vc_gitem-zone-a vc-gitem-zone-height-mode-auto vc-gitem-zone-height-mode-auto-4-3 vc_gitem-is-link\" style=\"background-image: url('https:\/\/lgbtq-insight-project.eu\/wp-content\/uploads\/2022\/10\/2022-10-11-120147-1024x576.jpeg') !important;\"><a href=\"https:\/\/lgbtq-insight-project.eu\/el\/transnational-project-meeting-in-salerno\/\" title=\"\u0394\u03b9\u03b1\u03ba\u03c1\u03b1\u03c4\u03b9\u03ba\u03ae \u03c3\u03c5\u03bd\u03ac\u03bd\u03c4\u03b7\u03c3\u03b7 \u03c4\u03bf\u03c5 \u03ad\u03c1\u03b3\u03bf\u03c5 \u03c3\u03c4\u03bf \u03a3\u03b1\u03bb\u03ad\u03c1\u03bd\u03bf\" class=\"vc_gitem-link vc-zone-link\" ><\/a><img src=\"https:\/\/lgbtq-insight-project.eu\/wp-content\/uploads\/2022\/10\/2022-10-11-120147-1024x576.jpeg\" class=\"vc_gitem-zone-img\" alt=\"2022-10-11-120147\"><div class=\"vc_gitem-zone-mini\"><\/div><\/div><\/div><div class=\"vc_gitem-zone vc_gitem-zone-c vc_custom_1419240516480\"><div class=\"vc_gitem-zone-mini\"><div class=\"vc_gitem_row vc_row vc_gitem-row-position-top\"><div class=\"vc_col-sm-12 vc_gitem-col vc_gitem-col-align-\"><div class=\"vc_custom_heading vc_gitem-post-data vc_gitem-post-data-source-post_title\" ><h4 style=\"text-align: left\" >\u0394\u03b9\u03b1\u03ba\u03c1\u03b1\u03c4\u03b9\u03ba\u03ae \u03c3\u03c5\u03bd\u03ac\u03bd\u03c4\u03b7\u03c3\u03b7 \u03c4\u03bf\u03c5 \u03ad\u03c1\u03b3\u03bf\u03c5 \u03c3\u03c4\u03bf \u03a3\u03b1\u03bb\u03ad\u03c1\u03bd\u03bf<\/h4><\/div><div class=\"vc_custom_heading vc_gitem-post-data vc_gitem-post-data-source-post_excerpt\" ><p style=\"text-align: left\" ><\/p><\/div><div class=\"vc_btn3-container vc_btn3-left\"><a class=\"vc_general vc_btn3 vc_btn3-size-md vc_btn3-shape-rounded vc_btn3-style-flat vc_btn3-color-juicy-pink\" a href=\"https:\/\/lgbtq-insight-project.eu\/el\/transnational-project-meeting-in-salerno\/\" title=\"\u0394\u03b9\u03ac\u03b2\u03b1\u03c3\u03b5\">\u0394\u03b9\u03ac\u03b2\u03b1\u03c3\u03b5<\/a><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"vc_clearfix\"><\/div><\/div><div class=\"vc_grid-item vc_clearfix vc_col-sm-6 vc_grid-item-zone-c-bottom\"><div class=\"vc_grid-item-mini vc_clearfix\"><div class=\"vc_gitem-animated-block\" ><div class=\"vc_gitem-zone vc_gitem-zone-a vc-gitem-zone-height-mode-auto vc-gitem-zone-height-mode-auto-4-3 vc_gitem-is-link\" style=\"background-image: url('https:\/\/lgbtq-insight-project.eu\/wp-content\/uploads\/2022\/07\/insight_post_1-1024x578.jpg') !important;\"><a href=\"https:\/\/lgbtq-insight-project.eu\/el\/insight-into-healthcare-system-inequalities-interview-with-lgbti-individuals-part-ii\/\" title=\"INSIGHT \u03c3\u03c4\u03b9\u03c2 \u03b1\u03bd\u03b9\u03c3\u03cc\u03c4\u03b7\u03c4\u03b5\u03c2 \u03c4\u03bf\u03c5 \u03c3\u03c5\u03c3\u03c4\u03ae\u03bc\u03b1\u03c4\u03bf\u03c2 \u03c5\u03b3\u03b5\u03b9\u03bf\u03bd\u03bf\u03bc\u03b9\u03ba\u03ae\u03c2 \u03c0\u03b5\u03c1\u03af\u03b8\u03b1\u03bb\u03c8\u03b7\u03c2: \u03a3\u03c5\u03bd\u03ad\u03bd\u03c4\u03b5\u03c5\u03be\u03b7 \u03bc\u03b5 \u039b\u039f\u0391\u03a4\u039a\u0399+ \u03ac\u03c4\u03bf\u03bc\u03b1, \u03bc\u03ad\u03c1\u03bf\u03c2 \u0399I\" class=\"vc_gitem-link vc-zone-link\" ><\/a><img src=\"https:\/\/lgbtq-insight-project.eu\/wp-content\/uploads\/2022\/07\/insight_post_1-1024x578.jpg\" class=\"vc_gitem-zone-img\" alt=\"insight_post_1\"><div class=\"vc_gitem-zone-mini\"><\/div><\/div><\/div><div class=\"vc_gitem-zone vc_gitem-zone-c vc_custom_1419240516480\"><div class=\"vc_gitem-zone-mini\"><div class=\"vc_gitem_row vc_row vc_gitem-row-position-top\"><div class=\"vc_col-sm-12 vc_gitem-col vc_gitem-col-align-\"><div class=\"vc_custom_heading vc_gitem-post-data vc_gitem-post-data-source-post_title\" ><h4 style=\"text-align: left\" >INSIGHT \u03c3\u03c4\u03b9\u03c2 \u03b1\u03bd\u03b9\u03c3\u03cc\u03c4\u03b7\u03c4\u03b5\u03c2 \u03c4\u03bf\u03c5 \u03c3\u03c5\u03c3\u03c4\u03ae\u03bc\u03b1\u03c4\u03bf\u03c2 \u03c5\u03b3\u03b5\u03b9\u03bf\u03bd\u03bf\u03bc\u03b9\u03ba\u03ae\u03c2 \u03c0\u03b5\u03c1\u03af\u03b8\u03b1\u03bb\u03c8\u03b7\u03c2: \u03a3\u03c5\u03bd\u03ad\u03bd\u03c4\u03b5\u03c5\u03be\u03b7 \u03bc\u03b5 \u039b\u039f\u0391\u03a4\u039a\u0399+ \u03ac\u03c4\u03bf\u03bc\u03b1, \u03bc\u03ad\u03c1\u03bf\u03c2 \u0399I<\/h4><\/div><div class=\"vc_custom_heading vc_gitem-post-data vc_gitem-post-data-source-post_excerpt\" ><p style=\"text-align: left\" ><\/p><\/div><div class=\"vc_btn3-container vc_btn3-left\"><a class=\"vc_general vc_btn3 vc_btn3-size-md vc_btn3-shape-rounded vc_btn3-style-flat vc_btn3-color-juicy-pink\" a href=\"https:\/\/lgbtq-insight-project.eu\/el\/insight-into-healthcare-system-inequalities-interview-with-lgbti-individuals-part-ii\/\" title=\"\u0394\u03b9\u03ac\u03b2\u03b1\u03c3\u03b5\">\u0394\u03b9\u03ac\u03b2\u03b1\u03c3\u03b5<\/a><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"vc_clearfix\"><\/div><\/div><div class=\"vc_grid-item vc_clearfix vc_col-sm-6 vc_grid-item-zone-c-bottom\"><div class=\"vc_grid-item-mini vc_clearfix\"><div class=\"vc_gitem-animated-block\" ><div class=\"vc_gitem-zone vc_gitem-zone-a vc-gitem-zone-height-mode-auto vc-gitem-zone-height-mode-auto-4-3 vc_gitem-is-link\" style=\"background-image: url('https:\/\/lgbtq-insight-project.eu\/wp-content\/uploads\/2022\/07\/Original-Articleenglish-version_ok-1_Page_1-728x1024.jpg') !important;\"><a href=\"https:\/\/lgbtq-insight-project.eu\/el\/representing-the-university-of-salerno-giulia-savarese-and-luna-carpinelli\/\" title=\"\u0395\u03ba\u03c0\u03c1\u03bf\u03c3\u03c9\u03c0\u03ce\u03bd\u03c4\u03b1\u03c2 \u03c4\u03bf \u03a0\u03b1\u03bd\u03b5\u03c0\u03b9\u03c3\u03c4\u03ae\u03bc\u03b9\u03bf \u03c4\u03bf\u03c5 \u03a3\u03b1\u03bb\u03ad\u03c1\u03bd\u03bf \n\u03a4\u03b6\u03bf\u03cd\u03bb\u03b9\u03b1 \u03a3\u03b1\u03b2\u03b1\u03c1\u03ad\u03b6\u03b5 \u03ba\u03b1\u03b9 \u039b\u03bf\u03cd\u03bd\u03b1 \u039a\u03b1\u03c1\u03c0\u03b9\u03bd\u03ad\u03bb\u03bb\u03b9\" class=\"vc_gitem-link vc-zone-link\" ><\/a><img src=\"https:\/\/lgbtq-insight-project.eu\/wp-content\/uploads\/2022\/07\/Original-Articleenglish-version_ok-1_Page_1-728x1024.jpg\" class=\"vc_gitem-zone-img\" alt=\"Original Article+english version_ok (1)_Page_1\"><div class=\"vc_gitem-zone-mini\"><\/div><\/div><\/div><div class=\"vc_gitem-zone vc_gitem-zone-c vc_custom_1419240516480\"><div class=\"vc_gitem-zone-mini\"><div class=\"vc_gitem_row vc_row vc_gitem-row-position-top\"><div class=\"vc_col-sm-12 vc_gitem-col vc_gitem-col-align-\"><div class=\"vc_custom_heading vc_gitem-post-data vc_gitem-post-data-source-post_title\" ><h4 style=\"text-align: left\" >\u0395\u03ba\u03c0\u03c1\u03bf\u03c3\u03c9\u03c0\u03ce\u03bd\u03c4\u03b1\u03c2 \u03c4\u03bf \u03a0\u03b1\u03bd\u03b5\u03c0\u03b9\u03c3\u03c4\u03ae\u03bc\u03b9\u03bf \u03c4\u03bf\u03c5 \u03a3\u03b1\u03bb\u03ad\u03c1\u03bd\u03bf \n\u03a4\u03b6\u03bf\u03cd\u03bb\u03b9\u03b1 \u03a3\u03b1\u03b2\u03b1\u03c1\u03ad\u03b6\u03b5 \u03ba\u03b1\u03b9 \u039b\u03bf\u03cd\u03bd\u03b1 \u039a\u03b1\u03c1\u03c0\u03b9\u03bd\u03ad\u03bb\u03bb\u03b9<\/h4><\/div><div class=\"vc_custom_heading vc_gitem-post-data vc_gitem-post-data-source-post_excerpt\" ><p style=\"text-align: left\" ><\/p><\/div><div class=\"vc_btn3-container vc_btn3-left\"><a class=\"vc_general vc_btn3 vc_btn3-size-md vc_btn3-shape-rounded vc_btn3-style-flat vc_btn3-color-juicy-pink\" a href=\"https:\/\/lgbtq-insight-project.eu\/el\/representing-the-university-of-salerno-giulia-savarese-and-luna-carpinelli\/\" title=\"\u0394\u03b9\u03ac\u03b2\u03b1\u03c3\u03b5\">\u0394\u03b9\u03ac\u03b2\u03b1\u03c3\u03b5<\/a><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"vc_clearfix\"><\/div><\/div><div class=\"vc_grid-item vc_clearfix vc_col-sm-6 vc_grid-item-zone-c-bottom\"><div class=\"vc_grid-item-mini vc_clearfix\"><div class=\"vc_gitem-animated-block\" ><div class=\"vc_gitem-zone vc_gitem-zone-a vc-gitem-zone-height-mode-auto vc-gitem-zone-height-mode-auto-4-3 vc_gitem-is-link\" style=\"background-image: url('https:\/\/lgbtq-insight-project.eu\/wp-content\/uploads\/2022\/07\/insight_post_1-1024x578.jpg') !important;\"><a href=\"https:\/\/lgbtq-insight-project.eu\/el\/insight-into-healthcare-system-inequalities-interview-with-lgbti-individuals-part-i\/\" title=\"INSIGHT \u03c3\u03c4\u03b9\u03c2 \u03b1\u03bd\u03b9\u03c3\u03cc\u03c4\u03b7\u03c4\u03b5\u03c2 \u03c4\u03bf\u03c5 \u03c3\u03c5\u03c3\u03c4\u03ae\u03bc\u03b1\u03c4\u03bf\u03c2 \u03c5\u03b3\u03b5\u03b9\u03bf\u03bd\u03bf\u03bc\u03b9\u03ba\u03ae\u03c2 \u03c0\u03b5\u03c1\u03af\u03b8\u03b1\u03bb\u03c8\u03b7\u03c2: \u03a3\u03c5\u03bd\u03ad\u03bd\u03c4\u03b5\u03c5\u03be\u03b7 \u03bc\u03b5 \u039b\u039f\u0391\u03a4\u039a\u0399+ \u03ac\u03c4\u03bf\u03bc\u03b1, \u03bc\u03ad\u03c1\u03bf\u03c2 \u0399\" class=\"vc_gitem-link vc-zone-link\" ><\/a><img src=\"https:\/\/lgbtq-insight-project.eu\/wp-content\/uploads\/2022\/07\/insight_post_1-1024x578.jpg\" class=\"vc_gitem-zone-img\" alt=\"insight_post_1\"><div class=\"vc_gitem-zone-mini\"><\/div><\/div><\/div><div class=\"vc_gitem-zone vc_gitem-zone-c vc_custom_1419240516480\"><div class=\"vc_gitem-zone-mini\"><div class=\"vc_gitem_row vc_row vc_gitem-row-position-top\"><div class=\"vc_col-sm-12 vc_gitem-col vc_gitem-col-align-\"><div class=\"vc_custom_heading vc_gitem-post-data vc_gitem-post-data-source-post_title\" ><h4 style=\"text-align: left\" >INSIGHT \u03c3\u03c4\u03b9\u03c2 \u03b1\u03bd\u03b9\u03c3\u03cc\u03c4\u03b7\u03c4\u03b5\u03c2 \u03c4\u03bf\u03c5 \u03c3\u03c5\u03c3\u03c4\u03ae\u03bc\u03b1\u03c4\u03bf\u03c2 \u03c5\u03b3\u03b5\u03b9\u03bf\u03bd\u03bf\u03bc\u03b9\u03ba\u03ae\u03c2 \u03c0\u03b5\u03c1\u03af\u03b8\u03b1\u03bb\u03c8\u03b7\u03c2: \u03a3\u03c5\u03bd\u03ad\u03bd\u03c4\u03b5\u03c5\u03be\u03b7 \u03bc\u03b5 \u039b\u039f\u0391\u03a4\u039a\u0399+ \u03ac\u03c4\u03bf\u03bc\u03b1, \u03bc\u03ad\u03c1\u03bf\u03c2 \u0399<\/h4><\/div><div class=\"vc_custom_heading vc_gitem-post-data vc_gitem-post-data-source-post_excerpt\" ><p style=\"text-align: left\" ><\/p><\/div><div class=\"vc_btn3-container vc_btn3-left\"><a class=\"vc_general vc_btn3 vc_btn3-size-md vc_btn3-shape-rounded vc_btn3-style-flat vc_btn3-color-juicy-pink\" a href=\"https:\/\/lgbtq-insight-project.eu\/el\/insight-into-healthcare-system-inequalities-interview-with-lgbti-individuals-part-i\/\" title=\"\u0394\u03b9\u03ac\u03b2\u03b1\u03c3\u03b5\">\u0394\u03b9\u03ac\u03b2\u03b1\u03c3\u03b5<\/a><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"vc_clearfix\"><\/div><\/div><div class=\"vc_grid-item vc_clearfix vc_col-sm-6 vc_grid-item-zone-c-bottom\"><div class=\"vc_grid-item-mini vc_clearfix\"><div class=\"vc_gitem-animated-block\" ><div class=\"vc_gitem-zone vc_gitem-zone-a vc-gitem-zone-height-mode-auto vc-gitem-zone-height-mode-auto-4-3 vc_gitem-is-link\" style=\"background-image: url('https:\/\/lgbtq-insight-project.eu\/wp-content\/uploads\/2022\/07\/insight_post_1-1024x578.jpg') !important;\"><a href=\"https:\/\/lgbtq-insight-project.eu\/el\/insight-had-a-solid-presence-at-the-athens-pride\/\" title=\"INSIGHT in Athens Pride 2022\" class=\"vc_gitem-link vc-zone-link\" ><\/a><img src=\"https:\/\/lgbtq-insight-project.eu\/wp-content\/uploads\/2022\/07\/insight_post_1-1024x578.jpg\" class=\"vc_gitem-zone-img\" alt=\"insight_post_1\"><div class=\"vc_gitem-zone-mini\"><\/div><\/div><\/div><div class=\"vc_gitem-zone vc_gitem-zone-c vc_custom_1419240516480\"><div class=\"vc_gitem-zone-mini\"><div class=\"vc_gitem_row vc_row vc_gitem-row-position-top\"><div class=\"vc_col-sm-12 vc_gitem-col vc_gitem-col-align-\"><div class=\"vc_custom_heading vc_gitem-post-data vc_gitem-post-data-source-post_title\" ><h4 style=\"text-align: left\" >INSIGHT in Athens Pride 2022<\/h4><\/div><div class=\"vc_custom_heading vc_gitem-post-data vc_gitem-post-data-source-post_excerpt\" ><p style=\"text-align: left\" ><\/p><\/div><div class=\"vc_btn3-container vc_btn3-left\"><a class=\"vc_general vc_btn3 vc_btn3-size-md vc_btn3-shape-rounded vc_btn3-style-flat vc_btn3-color-juicy-pink\" a href=\"https:\/\/lgbtq-insight-project.eu\/el\/insight-had-a-solid-presence-at-the-athens-pride\/\" title=\"\u0394\u03b9\u03ac\u03b2\u03b1\u03c3\u03b5\">\u0394\u03b9\u03ac\u03b2\u03b1\u03c3\u03b5<\/a><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"vc_clearfix\"><\/div><\/div><\/div><\/div>\n\t<\/div>\n<\/div><\/div><\/div><\/div><\/div>","protected":false},"excerpt":{"rendered":null,"protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"page-full.php","meta":{"footnotes":""},"_links":{"self":[{"href":"https:\/\/lgbtq-insight-project.eu\/el\/wp-json\/wp\/v2\/pages\/18"}],"collection":[{"href":"https:\/\/lgbtq-insight-project.eu\/el\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/lgbtq-insight-project.eu\/el\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/lgbtq-insight-project.eu\/el\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/lgbtq-insight-project.eu\/el\/wp-json\/wp\/v2\/comments?post=18"}],"version-history":[{"count":0,"href":"https:\/\/lgbtq-insight-project.eu\/el\/wp-json\/wp\/v2\/pages\/18\/revisions"}],"wp:attachment":[{"href":"https:\/\/lgbtq-insight-project.eu\/el\/wp-json\/wp\/v2\/media?parent=18"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}