{"id":13,"date":"2022-05-01T18:17:48","date_gmt":"2022-05-01T17:17:48","guid":{"rendered":"http:\/\/lgbtq-insight-project.eu\/?page_id=13"},"modified":"2024-01-25T16:25:40","modified_gmt":"2024-01-25T16:25:40","slug":"good-practices-guide","status":"publish","type":"page","link":"https:\/\/lgbtq-insight-project.eu\/it\/good-practices-guide\/","title":{"rendered":"Guida alle buone pratiche"},"content":{"rendered":"<div class=\"vc_row wpb_row vc_row-fluid\"><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p>La Guida alle buone pratiche:<\/p>\n<ul>\n<li>Fornire informazioni sui diritti umani relativi all'assistenza sanitaria e sui diritti delle persone LGBTI+.<\/li>\n<li>Riconoscere le disuguaglianze che le persone LGBTI+ incontrano nell'accesso al sistema sanitario.<\/li>\n<li>Fornire indicazioni alle agenzie e alle organizzazioni responsabili dell'assistenza alle persone LGBTI+.<\/li>\n<li>Fornire una guida ai professionisti e agli operatori che si occupano di persone LGBTI+.<\/li>\n<li>Scoprire strategie per integrare trattamenti inclusivi e rispettivi.<\/li>\n<\/ul>\n<p>L'elemento pi\u00f9 importante dell'innovazione di questo progetto \u00e8 la visione stessa di INSIGHT. Questa guida intende contribuire alla creazione di un sistema sanitario inclusivo, offrendo idee per nuove capacit\u00e0 e indicazioni su come eliminare le barriere, evitare comportamenti pregiudiziali e trovare il coraggio di sfidare gli atteggiamenti anti-LGBTI+.<\/p>\n\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><\/div><div class=\"vc_row wpb_row vc_row-fluid\"><div class=\"wpb_column vc_column_container vc_col-sm-4\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-4\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><style>.vc_btn3-style-gradient.vc_btn-gradient-btn-6a570c120ef1d:hover{color: #fff;background-color: #5472d2;border: none;background-position: 100% 0;}<\/style><style>.vc_btn3-style-gradient.vc_btn-gradient-btn-6a570c120ef1d{color: #fff;border: none;background-color: #00c1cf;background-image: -webkit-linear-gradient(left, #00c1cf 0%, #5472d2 50%,#00c1cf 100%);background-image: linear-gradient(to right, #00c1cf 0%, #5472d2 50%,#00c1cf 100%);-webkit-transition: all .2s ease-in-out;transition: all .2s ease-in-out;background-size: 200% 100%;}<\/style><div class=\"vc_btn3-container vc_btn3-inline\" id=\"gpgDownloadButton\" ><a data-vc-gradient-1=\"#00c1cf\" data-vc-gradient-2=\"#5472d2\" class=\"vc_general vc_btn3 vc_btn3-size-lg vc_btn3-shape-rounded vc_btn3-style-gradient vc_btn-gradient-btn-6a570c120ef1d\" href=\"https:\/\/lgbtq-insight-project.eu\/wp-content\/uploads\/2023\/11\/INSIGHT_PR1-Good-Practice-Guide-IT_final-version.pdf\" title=\"\" target=\"_blank\">Download della Guida<\/a><\/div><\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-4\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><\/div><\/div><\/div><\/div><div class=\"vc_row wpb_row vc_row-fluid\"><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"vc_empty_space\"   style=\"height: 32px\"><span class=\"vc_empty_space_inner\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"vc_row wpb_row vc_row-fluid\"><div class=\"wpb_column vc_column_container vc_col-sm-4\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-4\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><noscript class=\"ninja-forms-noscript-message\">\n\tAvviso: JavaScript \u00e8 obbligatorio per questo contenuto.<\/noscript>\n<div id=\"nf-form-3-cont\" class=\"nf-form-cont\" aria-live=\"polite\" aria-labelledby=\"nf-form-title-3\" aria-describedby=\"nf-form-errors-3\" role=\"form\">\n\n    <div class=\"nf-loading-spinner\"><\/div>\n\n<\/div>\n        <!-- That data is being printed as a workaround to page builders reordering the order of the scripts loaded-->\n        <script>var formDisplay=1;var nfForms=nfForms||[];var form=[];form.id='3';form.settings={\"objectType\":\"Form Setting\",\"editActive\":true,\"title\":\"Guide \",\"show_title\":0,\"allow_public_link\":0,\"embed_form\":\"\",\"clear_complete\":1,\"hide_complete\":1,\"default_label_pos\":\"above\",\"wrapper_class\":\"\",\"element_class\":\"\",\"form_title_heading_level\":\"3\",\"key\":\"\",\"add_submit\":1,\"currency\":\"\",\"unique_field_error\":\"A form with this value has already been submitted.\",\"logged_in\":false,\"not_logged_in_msg\":\"\",\"sub_limit_msg\":\"The form has reached its submission limit.\",\"calculations\":[],\"formContentData\":[\"how_would_you_rate_our_guide_1698924674037\",\"submit_1698924694069\"],\"changeEmailErrorMsg\":\"Immetti un indirizzo email valido.\",\"changeDateErrorMsg\":\"Please enter a valid date!\",\"confirmFieldErrorMsg\":\"Questi campi devono corrispondere.\",\"fieldNumberNumMinError\":\"Errore numero min\",\"fieldNumberNumMaxError\":\"Errore numero max\",\"fieldNumberIncrementBy\":\"Incrementa di \",\"formErrorsCorrectErrors\":\"Correggi gli errori prima di inviare il form.\",\"validateRequiredField\":\"Campo obbligatorio.\",\"honeypotHoneypotError\":\"Errore Honeypot\",\"fieldsMarkedRequired\":\"I campi contrassegnati con <span class=\\\"ninja-forms-req-symbol\\\">*<\\\/span> sono obbligatori.\",\"drawerDisabled\":false,\"ninjaForms\":\"Ninja Forms\",\"fieldTextareaRTEInsertLink\":\"Inserisci link\",\"fieldTextareaRTEInsertMedia\":\"Inserisci media\",\"fieldTextareaRTESelectAFile\":\"Seleziona un file\",\"formHoneypot\":\"Se sei un essere umano e vedi questo campo, lascialo vuoto.\",\"fileUploadOldCodeFileUploadInProgress\":\"Caricamento file in corso.\",\"fileUploadOldCodeFileUpload\":\"CARICAMENTO FILE\",\"currencySymbol\":\"&euro;\",\"thousands_sep\":\".\",\"decimal_point\":\",\",\"siteLocale\":\"it_IT\",\"dateFormat\":\"d\\\/m\\\/Y\",\"startOfWeek\":\"1\",\"of\":\"di\",\"previousMonth\":\"Previous Month\",\"nextMonth\":\"Next Month\",\"months\":[\"January\",\"February\",\"March\",\"April\",\"May\",\"June\",\"July\",\"August\",\"September\",\"October\",\"November\",\"December\"],\"monthsShort\":[\"Jan\",\"Feb\",\"Mar\",\"Apr\",\"May\",\"Jun\",\"Jul\",\"Aug\",\"Sep\",\"Oct\",\"Nov\",\"Dec\"],\"weekdays\":[\"Sunday\",\"Monday\",\"Tuesday\",\"Wednesday\",\"Thursday\",\"Friday\",\"Saturday\"],\"weekdaysShort\":[\"Sun\",\"Mon\",\"Tue\",\"Wed\",\"Thu\",\"Fri\",\"Sat\"],\"weekdaysMin\":[\"Su\",\"Mo\",\"Tu\",\"We\",\"Th\",\"Fr\",\"Sa\"],\"recaptchaConsentMissing\":\"reCaptcha validation couldn&#039;t load.\",\"recaptchaMissingCookie\":\"reCaptcha v3 validation couldn&#039;t load the cookie needed to submit the form.\",\"recaptchaConsentEvent\":\"Accept reCaptcha cookies before sending the form.\",\"currency_symbol\":\"\",\"beforeForm\":\"\",\"beforeFields\":\"\",\"afterFields\":\"\",\"afterForm\":\"\"};form.fields=[{\"objectType\":\"Field\",\"objectDomain\":\"fields\",\"editActive\":false,\"order\":999,\"idAttribute\":\"id\",\"type\":\"starrating\",\"label\":\"How would you rate our Guide?\",\"label_pos\":\"above\",\"default\":\"\",\"number_of_stars\":5,\"required\":0,\"container_class\":\"\",\"element_class\":\"\",\"key\":\"how_would_you_rate_our_guide_1698924674037\",\"admin_label\":\"\",\"value\":\"\",\"drawerDisabled\":false,\"id\":14,\"beforeField\":\"\",\"afterField\":\"\",\"parentType\":\"starrating\",\"element_templates\":[\"starrating\",\"input\"],\"old_classname\":\"\",\"wrap_template\":\"wrap\"},{\"objectType\":\"Field\",\"objectDomain\":\"fields\",\"editActive\":false,\"order\":9999,\"idAttribute\":\"id\",\"type\":\"submit\",\"label\":\"Submit\",\"processing_label\":\"Processing\",\"container_class\":\"\",\"element_class\":\"\",\"key\":\"submit_1698924694069\",\"id\":15,\"beforeField\":\"\",\"afterField\":\"\",\"value\":\"\",\"label_pos\":\"above\",\"parentType\":\"textbox\",\"element_templates\":[\"submit\",\"button\",\"input\"],\"old_classname\":\"\",\"wrap_template\":\"wrap-no-label\"}];nfForms.push(form);<\/script>\n        <\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-4\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><\/div><\/div><\/div><\/div>","protected":false},"excerpt":{"rendered":null,"protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"page-full.php","meta":{"footnotes":""},"_links":{"self":[{"href":"https:\/\/lgbtq-insight-project.eu\/it\/wp-json\/wp\/v2\/pages\/13"}],"collection":[{"href":"https:\/\/lgbtq-insight-project.eu\/it\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/lgbtq-insight-project.eu\/it\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/lgbtq-insight-project.eu\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/lgbtq-insight-project.eu\/it\/wp-json\/wp\/v2\/comments?post=13"}],"version-history":[{"count":0,"href":"https:\/\/lgbtq-insight-project.eu\/it\/wp-json\/wp\/v2\/pages\/13\/revisions"}],"wp:attachment":[{"href":"https:\/\/lgbtq-insight-project.eu\/it\/wp-json\/wp\/v2\/media?parent=13"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}